{"id":4705,"date":"2022-04-11T19:32:15","date_gmt":"2022-04-12T00:32:15","guid":{"rendered":"https:\/\/matehualasinmiedo.com\/?p=4705"},"modified":"2022-04-11T19:32:18","modified_gmt":"2022-04-12T00:32:18","slug":"san-luis-potosi-respalda-propuesta-federal-de-servicio-medico-universal","status":"publish","type":"post","link":"https:\/\/matehualasinmiedo.com\/index.php\/2022\/04\/11\/san-luis-potosi-respalda-propuesta-federal-de-servicio-medico-universal\/","title":{"rendered":"SAN LUIS POTOS\u00cd RESPALDA PROPUESTA FEDERAL DE SERVICIO M\u00c9DICO UNIVERSAL"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4706\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-1024x683.jpg\" alt=\"\" class=\"wp-image-4706\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/1-64.jpg 1473w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>El Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona anunci\u00f3 que la Entidad se suma al proyecto de Andr\u00e9s Manuel L\u00f3pez Obrador de brindar atenci\u00f3n m\u00e9dica y medicamentos gratuitos sin distingos a las y los potosinos.<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">San Luis Potos\u00ed se sumar\u00e1 al proyecto del servicio m\u00e9dico universal del Presidente Andr\u00e9s Manuel L\u00f3pez Obrador para beneficiar a los casi 3 millones de habitantes en el Estado, por lo que se est\u00e1 en acuerdos con el ejecutivo Federal para que los hospitales y cl\u00ednicas estatales sean manejados por el IMSS y la Secretar\u00eda de Bienestar y brinden medicinas y servicio gratuito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En reuni\u00f3n privada con el Presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, el Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona trat\u00f3 temas de vital importancia como la incorporaci\u00f3n del Estado al proyecto federal de homologar el sistema de salud, con el cual, los hospitales estatales pasar\u00edan a manos del Instituto Mexicano del Seguro Social (IMSS) y Secretar\u00eda de Bienestar para que todas y todos los potosinos reciban atenci\u00f3n m\u00e9dica gratuita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cTendr\u00edamos mejores medicamentos gratuitos, mejores equipamientos, pero sobre todo se federalizar\u00eda la n\u00f3mina estatal\u201d, expres\u00f3 Gallardo Cardona a los medios nacionales al t\u00e9rmino de la reuni\u00f3n con el Presidente, a\u00f1adiendo que todo el personal m\u00e9dico del sistema de salud estatal pasar\u00eda a la n\u00f3mina federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Mandatario explic\u00f3 que, de concretarse este proyecto, se respetar\u00e1n a cabalidad los derechos laborales y salariales obtenidos previamente por m\u00e1s de ocho mil doctoras, m\u00e9dicos, enfermeras y personal administrativo en la Entidad y ser\u00e1 la Federaci\u00f3n responsable del sistema de salud en todo el territorio potosino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro de los temas abordados entre Ricardo Gallardo Cardona y el presidente de M\u00e9xico L\u00f3pez Obrador fueron las cerca de 100 mil vacunas Covid de refuerzo que en breve recibir\u00e1 San Luis Potos\u00ed para continuar con el combate a la pandemia en las cuatro zonas del Estado. \u201cNo bajaremos la guardia en este tema y seguiremos aplicando los protocolos sanitarios correspondientes durante y despu\u00e9s de la temporada vacacional de Semana Santa\u201d, afirm\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"480\" style=\"aspect-ratio: 848 \/ 480;\" width=\"848\" controls src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2022\/04\/WhatsApp-Video-2022-04-11-at-5.43.31-PM.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona anunci\u00f3 que la Entidad se suma al proyecto de Andr\u00e9s Manuel L\u00f3pez Obrador de brindar atenci\u00f3n m\u00e9dica y medicamentos gratuitos sin distingos a las y los potosinos. San Luis Potos\u00ed se sumar\u00e1 al proyecto del servicio m\u00e9dico universal del Presidente Andr\u00e9s Manuel L\u00f3pez Obrador para beneficiar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-4705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slp","tag-slp"],"_links":{"self":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/4705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4705"}],"version-history":[{"count":1,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/4705\/revisions"}],"predecessor-version":[{"id":4708,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/4705\/revisions\/4708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media\/4706"}],"wp:attachment":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/categories?post=4705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/tags?post=4705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}