{"id":26679,"date":"2024-01-16T14:30:39","date_gmt":"2024-01-16T20:30:39","guid":{"rendered":"https:\/\/matehualasinmiedo.com\/?p=26679"},"modified":"2024-01-16T14:30:40","modified_gmt":"2024-01-16T20:30:40","slug":"gobierno-organiza-mas-de-15-eventos-por-dia-nacional-de-los-humedales","status":"publish","type":"post","link":"https:\/\/matehualasinmiedo.com\/index.php\/2024\/01\/16\/gobierno-organiza-mas-de-15-eventos-por-dia-nacional-de-los-humedales\/","title":{"rendered":"GOBIERNO ORGANIZA M\u00c1S DE 15 EVENTOS POR D\u00cdA NACIONAL DE LOS HUMEDALES"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" data-id=\"26680\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60-1024x538.jpg\" alt=\"\" class=\"wp-image-26680\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60-1024x538.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60-600x315.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60-300x158.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60-768x403.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2024\/01\/1-60.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, prepara cursos, talleres y actividades sobre protecci\u00f3n a los ecosistemas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno del Estado, con el apoyo de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh) y en coordinaci\u00f3n con instituciones de investigaci\u00f3n y asociaciones civiles, llevar\u00e1n a cabo en San Luis Potos\u00ed, m\u00e1s de 15 eventos, cursos y ense\u00f1anzas para el cuidado del Medio Ambiente, en el marco de la celebraci\u00f3n nacional del D\u00eda Mundial de los Humedales, a partir del 2 de febrero de 2024.<br>La titular de la Sedarh, Marcela Quevedo Pati\u00f1o, inform\u00f3 que como lo ha instruido el Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, de impulsar acciones que brinden apoyo en el cuidado del medio ambiente y de concientizaci\u00f3n sobre los ecosistemas de humedales y su importancia para la humanidad, el Estado fue elegido para llevar a cabo este magno evento en el que participar\u00e1n funcionarios e investigadores de todo M\u00e9xico.<br>Detall\u00f3 que, la celebraci\u00f3n ser\u00e1 durante febrero, en las cuatro regiones e iniciar\u00e1 con el evento inaugural en el museo Laberinto de las Ciencias y las Artes en la capital, para posteriormente en los siguientes d\u00edas visitar el manantial Los Peroles de Rioverde; La Media Luna; la Ci\u00e9nega de Cabezas de Tamasopo, entre otros municipios que cuentan con este ecosistema.<br>La Organizaci\u00f3n Vida Silvestre (OVIS) representada por Karla Logan L\u00f3pez, expondr\u00e1 la situaci\u00f3n que existe en los sitios Ramsar de La Ci\u00e9nega de Cabezas y canales del ejido Tanchach\u00edn, de Aquism\u00f3n, mientras que El Laberinto Itinerante impartir\u00e1 talleres de microscop\u00eda y de creaci\u00f3n de peque\u00f1os humedales, as\u00ed como la Facultad de Agronom\u00eda de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) dictar\u00e1 conferencias sobre agricultura sustentable y medio ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, prepara cursos, talleres y actividades sobre protecci\u00f3n a los ecosistemas El Gobierno del Estado, con el apoyo de la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh) y en coordinaci\u00f3n con instituciones de investigaci\u00f3n y asociaciones civiles, llevar\u00e1n a cabo en San Luis Potos\u00ed, m\u00e1s de 15 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-26679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slp","tag-slp"],"_links":{"self":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/26679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/comments?post=26679"}],"version-history":[{"count":1,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/26679\/revisions"}],"predecessor-version":[{"id":26681,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/26679\/revisions\/26681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media\/26680"}],"wp:attachment":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media?parent=26679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/categories?post=26679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/tags?post=26679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}