{"id":19079,"date":"2023-05-10T16:44:44","date_gmt":"2023-05-10T21:44:44","guid":{"rendered":"https:\/\/matehualasinmiedo.com\/?p=19079"},"modified":"2023-05-10T16:46:36","modified_gmt":"2023-05-10T21:46:36","slug":"mamas-matehualenses-abarrotan-festival-del-dia-de-las-madres-organizado-por-el-gobierno-municipal-de-matehuala","status":"publish","type":"post","link":"https:\/\/matehualasinmiedo.com\/index.php\/2023\/05\/10\/mamas-matehualenses-abarrotan-festival-del-dia-de-las-madres-organizado-por-el-gobierno-municipal-de-matehuala\/","title":{"rendered":"MAM\u00c1S MATEHUALENSES ABARROTAN FESTIVAL DEL DIA DE LAS MADRES ORGANIZADO POR EL GOBIERNO MUNICIPAL DE MATEHUALA."},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" data-id=\"19080\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28-1024x538.jpg\" alt=\"\" class=\"wp-image-19080\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28-1024x538.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28-600x315.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28-300x158.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28-768x403.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/2-28.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19081\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-1024x683.jpg\" alt=\"\" class=\"wp-image-19081\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/3-24.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"19082\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-683x1024.jpg\" alt=\"\" class=\"wp-image-19082\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-683x1024.jpg 683w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-600x900.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-200x300.jpg 200w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-768x1152.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22-1024x1536.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/4-22.jpg 1067w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19083\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-1024x683.jpg\" alt=\"\" class=\"wp-image-19083\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/5-16.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19084\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-1024x683.jpg\" alt=\"\" class=\"wp-image-19084\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/6-10.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19085\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-1024x683.jpg\" alt=\"\" class=\"wp-image-19085\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/7-8.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19086\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-1024x683.jpg\" alt=\"\" class=\"wp-image-19086\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/8-7.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19087\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-1024x683.jpg\" alt=\"\" class=\"wp-image-19087\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/9-4.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19088\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-1024x683.jpg\" alt=\"\" class=\"wp-image-19088\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/10-2.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19089\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-1024x683.jpg\" alt=\"\" class=\"wp-image-19089\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/11-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"19090\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-1024x683.jpg\" alt=\"\" class=\"wp-image-19090\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-1024x683.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-1536x1024.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/12-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"19091\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-1024x682.jpg\" alt=\"\" class=\"wp-image-19091\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-1024x682.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-1536x1023.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/13-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"19092\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-1024x682.jpg\" alt=\"\" class=\"wp-image-19092\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-1024x682.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-600x400.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-300x200.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-768x512.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-1536x1023.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/05\/14-1.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No hay d\u00eda que no se llegue ni plazo que no se cumpla, y lleg\u00f3 el d\u00eda de celebrar a las mam\u00e1s de Matehuala con un magno festival organizado por el Gobierno Municipal presidido por el Ing. Iv\u00e1n Estrada Guzm\u00e1n, el cual se desarroll\u00f3 con gran \u00e9xito la tarde-noche de este martes 9 de Mayo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde temprana hora fueron miles de madres de familias acompa\u00f1adas y arropadas con gran cari\u00f1o pros sus seres queridos, hicieron su arrib\u00f3 a las instalaciones de Ferema, para disfrutar de un espectacular programa art\u00edstico, no sin antes retar a la suerte depositando sus boletos para participar en las rifas que se celebrar\u00edan m\u00e1s tarde donde decenas de mam\u00e1s fueron las agraciadas de ser acreedoras a grandes premios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ambiente de felicidad y algarab\u00eda predomino durante todo el evento, el cual fue abierto por el dueto musical potosino, Ana y David, quienes fueron los encargados recibir musicalmente a todos y todos los asistentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al filo de las 9 de la noche hizo su arrib\u00f3 al magno escenario el Ing. Iv\u00e1n Estrada Guzm\u00e1n, quien era esperado en el mismo, por su madre y esposa, a quienes abraz\u00f3 y felicit\u00f3 efusivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posterior a esto, el Presidente Municipal, decidi\u00f3 bajar del escenario y entre los miles de asistentes dirigir un emotivo mensaje cercano y de cara a la poblaci\u00f3n quien lo arrop\u00f3 y respaldo en todo momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan datos proporcionados por las corporaciones de auxilio se cont\u00f3 una afluencia superior a los 14 mil asistentes, los cuales disfrutaron del platillo fuerte de la noche como fue la presentaci\u00f3n del Grupo internacional \u201cLos Acosta\u201d quienes a lo largo de 2 horas hicieron vibrar con su m\u00fasica a los asistentes, especialmente a las mam\u00e1s que efusivamente coreaban sus canciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al primer minuto, ya del d\u00eda 10 de mayo fueron interpretadas las ma\u00f1anitas para todas las madres de familia extraordinariamente por el mariachi \u201cmi ciudad y sus tequileras\u201d acompa\u00f1ados por un espect\u00e1culo de pirot\u00e9cnica con el cual concluy\u00f3 esta gran celebraci\u00f3n del d\u00eda de las madres emprendido por el Ing. Iv\u00e1n Estrada Guzm\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay d\u00eda que no se llegue ni plazo que no se cumpla, y lleg\u00f3 el d\u00eda de celebrar a las mam\u00e1s de Matehuala con un magno festival organizado por el Gobierno Municipal presidido por el Ing. Iv\u00e1n Estrada Guzm\u00e1n, el cual se desarroll\u00f3 con gran \u00e9xito la tarde-noche de este martes 9 de Mayo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[13],"class_list":["post-19079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-matehuala","tag-matehuala"],"_links":{"self":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/19079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/comments?post=19079"}],"version-history":[{"count":1,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/19079\/revisions"}],"predecessor-version":[{"id":19093,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/19079\/revisions\/19093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media\/19080"}],"wp:attachment":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media?parent=19079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/categories?post=19079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/tags?post=19079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}