{"id":16446,"date":"2023-02-14T15:46:38","date_gmt":"2023-02-14T21:46:38","guid":{"rendered":"https:\/\/matehualasinmiedo.com\/?p=16446"},"modified":"2023-02-14T15:46:40","modified_gmt":"2023-02-14T21:46:40","slug":"convenio-de-seguridad-con-zacatecas-ya-arroja-resultados-vse","status":"publish","type":"post","link":"https:\/\/matehualasinmiedo.com\/index.php\/2023\/02\/14\/convenio-de-seguridad-con-zacatecas-ya-arroja-resultados-vse\/","title":{"rendered":"Convenio de seguridad con Zacatecas ya arroja resultados: VSE."},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"687\" data-id=\"16447\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-1024x687.jpg\" alt=\"\" class=\"wp-image-16447\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-1024x687.jpg 1024w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-600x402.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-300x201.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-768x515.jpg 768w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-1536x1030.jpg 1536w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51-272x182.jpg 272w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/1-51.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"878\" height=\"577\" data-id=\"16448\" src=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/2-51.jpg\" alt=\"\" class=\"wp-image-16448\" srcset=\"https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/2-51.jpg 878w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/2-51-600x394.jpg 600w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/2-51-300x197.jpg 300w, https:\/\/matehualasinmiedo.com\/wp-content\/uploads\/2023\/02\/2-51-768x505.jpg 768w\" sizes=\"auto, (max-width: 878px) 100vw, 878px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se logr\u00f3 el aseguramiento de m\u00e1s de 4 mil dosis de droga y la detenci\u00f3n de una pareja por el delito de narcomenudeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derivado del liderazgo asumido por el Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, para fortalecer los lazos en temas de seguridad con la entidad zacatecana y proteger la integridad de las y los potosinos, agentes de la Guardia Civil Estatal realizaron el aseguramiento de 3 mil dosis de cristal y mil 340 dosis de marihuana, en la carretera federal 49, Salinas de Hidalgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante los recorridos de vigilancia, los agentes estatales identificaron un automotor con placas del Estado de Zacatecas, que presentaba reporte por robos cometidos en una gasolinera ubicada en la zona; al acercarse a inspeccionar, los tripulantes -una mujer y un hombre- ofrecieron dinero a los polic\u00edas para evitar ser detenidos, al no aceptarlo, continuaron con la revisi\u00f3n, localizando los estupefacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos responden a los nombres de Ram\u00f3n \u201cN\u201d y Citlaly \u201cN\u201d, ambos menores de 30 a\u00f1os, presuntamente son parte de una organizaci\u00f3n criminal dedicada a la distribuci\u00f3n de drogas en el municipio de Salinas de Hidalgo y ya se encuentran a disposici\u00f3n de la Fiscal\u00eda General del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte del convenio firmado en la \u201cReuni\u00f3n de Coordinaci\u00f3n Interestatal para la Construcci\u00f3n de la Paz y Seguridad\u201d, entre San Luis Potos\u00ed y Zacatecas, el Gobierno del Cambio refrenda su compromiso de reducir los \u00edndices delictivos en el estado, ir de la mano con las entidades colindantes para fortalecer la estrategia de seguridad e inhibir la venta de drogas en las calles para que no llegue al consumo de las y los habitantes potosinos, inform\u00f3 en Vocero de Seguridad, Miguel Gallegos Cepeda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se logr\u00f3 el aseguramiento de m\u00e1s de 4 mil dosis de droga y la detenci\u00f3n de una pareja por el delito de narcomenudeo. Derivado del liderazgo asumido por el Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, para fortalecer los lazos en temas de seguridad con la entidad zacatecana y proteger la integridad de las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-16446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slp","tag-slp"],"_links":{"self":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/16446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/comments?post=16446"}],"version-history":[{"count":1,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/16446\/revisions"}],"predecessor-version":[{"id":16449,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/posts\/16446\/revisions\/16449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media\/16447"}],"wp:attachment":[{"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/media?parent=16446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/categories?post=16446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/matehualasinmiedo.com\/index.php\/wp-json\/wp\/v2\/tags?post=16446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}